{"id":226,"date":"2023-12-21T22:47:16","date_gmt":"2023-12-21T22:47:16","guid":{"rendered":"https:\/\/kioskodeprensa.online\/?p=226"},"modified":"2023-12-21T22:47:18","modified_gmt":"2023-12-21T22:47:18","slug":"la-gestion-del-alcalde-eduardo-cortes-promesas-incumplidas-y-resultados-frustrantes","status":"publish","type":"post","link":"https:\/\/kioskodeprensa.online\/index.php\/2023\/12\/21\/la-gestion-del-alcalde-eduardo-cortes-promesas-incumplidas-y-resultados-frustrantes\/","title":{"rendered":"La Gesti\u00f3n del Alcalde Eduardo Cort\u00e9s: Promesas Incumplidas y Resultados Frustrantes"},"content":{"rendered":"<p>El balance de la gesti\u00f3n del mandatario Eduardo Cort\u00e9s est\u00e1 marcado por la brecha entre las promesas realizadas y los resultados tangibles, especialmente en sectores clave como educaci\u00f3n, vivienda y seguridad.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-227\" src=\"http:\/\/kioskodeprensa.online\/wp-content\/uploads\/2023\/12\/acacias-meta-colombia.jpg\" alt=\"\" width=\"848\" height=\"565\" srcset=\"https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2023\/12\/acacias-meta-colombia.jpg 848w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2023\/12\/acacias-meta-colombia-300x200.jpg 300w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2023\/12\/acacias-meta-colombia-768x512.jpg 768w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2023\/12\/acacias-meta-colombia-150x100.jpg 150w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2023\/12\/acacias-meta-colombia-696x464.jpg 696w\" sizes=\"auto, (max-width: 848px) 100vw, 848px\" \/><\/p>\n<p>A solo un mes de concluir su mandato, la percepci\u00f3n de la ciudadan\u00eda ante la gesti\u00f3n del alcalde de Acac\u00edas, Eduardo Cort\u00e9s, no es positiva. En una entrevista con el concejal Gildardo Santos, se revelaron detalles sobre el desempe\u00f1o de Cort\u00e9s durante los \u00faltimos cuatro a\u00f1os, destacando que se qued\u00f3 &#8220;corto&#8221; en un 50% en el cumplimiento del Plan de Desarrollo.<\/p>\n<p>Santos subray\u00f3 que la comunidad tiene una percepci\u00f3n clara de la gesti\u00f3n, ya que, a pesar de las promesas prometedoras en el Programa de Gobierno que lo llev\u00f3 al cargo, estas no se materializaron en la realidad.<\/p>\n<p>Durante su mandato, Cort\u00e9s habr\u00eda prometido obras significativas en \u00e1reas como educaci\u00f3n, deporte, turismo y comercio, sin embargo, seg\u00fan Santos, estas promesas quedaron en solo discurso. Incluso, al revisar el Plan de Desarrollo aprobado por el Concejo Municipal, Peri\u00f3dico del Meta pudo constatar la ausencia de varias obras importantes para el progreso de Acac\u00edas, las cuales a\u00fan no se han concretado hasta la fecha.<\/p>\n<p>Proyectos fundamentales, entre ellos la edificaci\u00f3n de un Campus universitario con enfoque t\u00e9cnico y tecnol\u00f3gico, la creaci\u00f3n del complejo deportivo de la Villa Ol\u00edmpica, la implementaci\u00f3n de un sistema de telef\u00e9rico tur\u00edstico, la concepci\u00f3n de un parque tem\u00e1tico, la renovaci\u00f3n de la Plaza Central, e incluso la puesta en marcha de un Centro de Desarrollo Infantil, se quedaron estancados en el terreno de las promesas incumplidas.<\/p>\n<p>La educaci\u00f3n, uno de los pilares fundamentales para el desarrollo de una sociedad, ha sido uno de los sectores m\u00e1s afectados por la gesti\u00f3n de Cort\u00e9s. A pesar de las promesas de mejorar la calidad de la educaci\u00f3n y construir un Campus universitario, los estudiantes siguen enfrentando problemas de infraestructura y falta de recursos. El incumplimiento de estas promesas ha dejado a la juventud de Acac\u00edas sin las oportunidades que se les hab\u00edan prometido.<\/p>\n<p>Otro sector que ha sufrido las consecuencias de la gesti\u00f3n deficiente es el deporte. La creaci\u00f3n del complejo deportivo de la Villa Ol\u00edmpica era una promesa que generaba expectativas en la comunidad, pero hasta ahora solo ha quedado en palabras. Los j\u00f3venes deportistas de Acac\u00edas contin\u00faan sin tener un lugar adecuado para entrenar y desarrollar su talento.<\/p>\n<p>En cuanto al turismo, la implementaci\u00f3n de un sistema de telef\u00e9rico tur\u00edstico y la concepci\u00f3n de un parque tem\u00e1tico eran proyectos que promet\u00edan impulsar la econom\u00eda local y atraer visitantes. Sin embargo, estos proyectos no han avanzado y Acac\u00edas sigue sin aprovechar todo su potencial tur\u00edstico.<\/p>\n<p>La seguridad tambi\u00e9n ha sido un tema pendiente durante la gesti\u00f3n de Cort\u00e9s. A pesar de las promesas de mejorar la seguridad ciudadana, los \u00edndices de criminalidad siguen siendo altos en Acac\u00edas. Los ciudadanos se sienten inseguros y desprotegidos, sin ver resultados concretos en esta \u00e1rea.<\/p>\n<p>En resumen, la gesti\u00f3n del alcalde Eduardo Cort\u00e9s en Acac\u00edas ha estado marcada por promesas incumplidas y resultados frustrantes. La falta de obras importantes y la ausencia de mejoras significativas en sectores clave como educaci\u00f3n, deporte, turismo y seguridad han dejado a la comunidad desilusionada. Es evidente que las palabras no se tradujeron en acciones concretas durante este mandato.<\/p>\n<p>La ciudadan\u00eda merece un liderazgo comprometido y capaz de cumplir con lo prometido. Esperemos que el pr\u00f3ximo alcalde pueda aprender de los errores de esta gesti\u00f3n y trabajar realmente por el progreso y bienestar de Acac\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El balance de la gesti\u00f3n del mandatario Eduardo Cort\u00e9s est\u00e1 marcado por la brecha entre las promesas realizadas y los resultados tangibles, especialmente en sectores clave como educaci\u00f3n, vivienda y seguridad. A solo un mes de concluir su mandato, la percepci\u00f3n de la ciudadan\u00eda ante la gesti\u00f3n del alcalde de Acac\u00edas, Eduardo Cort\u00e9s, no es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,13],"tags":[29,28,26,27,30],"class_list":{"0":"post-226","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales-meta","8":"category-politica","9":"tag-deporte","10":"tag-educacion","11":"tag-gestion-del-alcalde","12":"tag-promesas-incumplidas","13":"tag-turismo"},"_links":{"self":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/comments?post=226"}],"version-history":[{"count":1,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/226\/revisions"}],"predecessor-version":[{"id":228,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/226\/revisions\/228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media\/227"}],"wp:attachment":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media?parent=226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/categories?post=226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/tags?post=226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}