{"id":635,"date":"2024-07-03T13:14:55","date_gmt":"2024-07-03T13:14:55","guid":{"rendered":"https:\/\/kioskodeprensa.online\/?p=635"},"modified":"2024-07-03T13:14:57","modified_gmt":"2024-07-03T13:14:57","slug":"comunicado-de-prensa","status":"publish","type":"post","link":"https:\/\/kioskodeprensa.online\/index.php\/2024\/07\/03\/comunicado-de-prensa\/","title":{"rendered":"Comunicado de Prensa"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>No 20- Julio 03 de 2024<\/p>\n\n\n\n<p>MESA DE DI\u00c1LOGO ENTRE ECOPETROL, ALCALD\u00cdA Y COMUNIDAD DE LA VEREDA CHICHIMENE<\/p>\n\n\n\n<p>En <a><\/a>la noche del d\u00eda anterior, representantes de Ecopetrol, el Alcalde Municipal, el Secretario Privado y el Jefe de Contrataci\u00f3n se reunieron en el Complejo Deportivo de Chichimene con la comunidad local para abordar la revisi\u00f3n del convenio destinado a la reconstrucci\u00f3n del complejo deportivo del sector.<\/p>\n\n\n\n<p>El convenio actual requiere ajustes t\u00e9cnicos adicionales, lo cual demanda una revisi\u00f3n exhaustiva desde los \u00e1mbitos jur\u00eddico, t\u00e9cnico y administrativo. Tanto la administraci\u00f3n municipal como Ecopetrol reafirman su compromiso de convertir este proyecto en una realidad que beneficie directamente a la comunidad.<\/p>\n\n\n\n<p>El Alcalde Municipal y su equipo han mostrado un firme compromiso con las comunidades locales y han expresado la voluntad pol\u00edtica necesaria para asegurar la viabilidad y la continuidad del convenio. A pesar de algunos presuntos incumplimientos por parte de administraciones anteriores, se ha subrayado la posibilidad jur\u00eddica de llevar a cabo las modificaciones necesarias para optimizar los tiempos de ejecuci\u00f3n del proyecto.<\/p>\n\n\n\n<p>En aras de avanzar en la recuperaci\u00f3n de proyectos de la anterior vigencia que beneficien a la comunidad, se organizar\u00e1n mesas de trabajo conjuntas con los equipos jur\u00eddicos de la administraci\u00f3n municipal y de Ecopetrol. Esta colaboraci\u00f3n estrecha permitir\u00e1 abordar de manera efectiva los desaf\u00edos presentes y garantizar el \u00e9xito del convenio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No 20- Julio 03 de 2024 MESA DE DI\u00c1LOGO ENTRE ECOPETROL, ALCALD\u00cdA Y COMUNIDAD DE LA VEREDA CHICHIMENE En la noche del d\u00eda anterior, representantes de Ecopetrol, el Alcalde Municipal, el Secretario Privado y el Jefe de Contrataci\u00f3n se reunieron en el Complejo Deportivo de Chichimene con la comunidad local para abordar la revisi\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-635","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-blog"},"_links":{"self":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/comments?post=635"}],"version-history":[{"count":2,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/635\/revisions"}],"predecessor-version":[{"id":641,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/635\/revisions\/641"}],"wp:attachment":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media?parent=635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/categories?post=635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/tags?post=635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}