{"id":728,"date":"2024-11-12T14:26:51","date_gmt":"2024-11-12T14:26:51","guid":{"rendered":"https:\/\/kioskodeprensa.online\/?p=728"},"modified":"2024-11-12T14:26:53","modified_gmt":"2024-11-12T14:26:53","slug":"el-jefe-de-estado-se-pronuncio-tras-combates-en-el-meta-dijo-que-el-jefe-disidente-decidio-convertirse-en-miembro-de-la-junta-del-narcotrafico-en-lugar-de-hacer-la-paz","status":"publish","type":"post","link":"https:\/\/kioskodeprensa.online\/index.php\/2024\/11\/12\/el-jefe-de-estado-se-pronuncio-tras-combates-en-el-meta-dijo-que-el-jefe-disidente-decidio-convertirse-en-miembro-de-la-junta-del-narcotrafico-en-lugar-de-hacer-la-paz\/","title":{"rendered":"El jefe de Estado se pronunci\u00f3 tras combates en el Meta. Dijo que el jefe disidente decidi\u00f3 convertirse en miembro de la Junta del Narcotr\u00e1fico en lugar de hacer la paz"},"content":{"rendered":"\n<p>El presidente<strong>\u00a0Gustavo Petro asegur\u00f3 que alias Iv\u00e1n Mordisco, jefe de una facci\u00f3n de las disidencias de las Farc, est\u00e1 arrinconado.\u00a0<\/strong><\/p>\n\n\n\n<p>El mandatario se pronunci\u00f3 en la tarde del domingo 10 de octubre, 24 horas despu\u00e9s de que el Ej\u00e9rcito dio de baja a 10 disidentes al mando de &#8216;Mordisco&#8217; durante unos combates en el departamento del Meta.\u00a0<\/p>\n\n\n\n<p>&#8220;Aqu\u00ed logramos un triunfo y un verdadero desastre militar sobre alias Mordisco, que prefiri\u00f3 convertirse en miembro de la Junta del Narcotr\u00e1fico, sin que lo supieran sus compa\u00f1eros, a hacer la paz con el Gobierno. Perdieron los fusiles y pertrechos que tra\u00edan del Cauca para asegurar rutas de colt\u00e1n y coca\u00edna en la Amazon\u00eda&#8221;, se\u00f1al\u00f3 el jefe de Estado en su cuenta de X, donde hizo una larga reflexi\u00f3n sobre la decisi\u00f3n de &#8216;Iv\u00e1n Mordisco&#8217; de no continuar con el proceso de paz.<\/p>\n\n\n\n<p>&#8220;Le recomiendo a &#8216;Mordisco&#8217; verse la pel\u00edcula sobre la autobiograf\u00eda de Mandela que esta en Prime.<strong>&nbsp;Al menos podr\u00eda captar as\u00ed sea de lejos, el verdadero valor revolucionario de la paz, se que a\u00fan arrinconado, puede v\u00e9rsela&#8221;,<\/strong>&nbsp;dijo el jefe de Estado.<\/p>\n\n\n\n<p>Y es que al inicio de este gobierno, cuando el presidente Petro puso sobre la mesa la pol\u00edtica de &#8216;paz total&#8217;, incluso se dio un cese del fuego con el llamado Estado Mayor Central de las Farc, liderado por &#8216;Mordisco&#8217;, pero este no dio se\u00f1ales de paz y, por el contrario, perpetr\u00f3 decenas de atentados principalmente en el Cauca contra la Fuerza P\u00fablica y la poblaci\u00f3n.<\/p>\n\n\n\n<p>El presidente Petro, sin embargo, asever\u00f3 que las bajas no son ning\u00fan bot\u00edn de guerra y lament\u00f3 que las estructuras criminales podr\u00e1n reclutar f\u00e1cilmente a nuevos j\u00f3venes debido a las condiciones de pobreza que enfrentan.\u00a0\u00a0<\/p>\n\n\n\n<p><strong>&#8220;M\u00e1s que los cuerpos y cad\u00e1veres, que no es bot\u00edn de guerra en ninguna circunstancia, y que a las actuales organizaciones armadas no les importan por que reemplazan los muertos por otros j\u00f3venes, dada la pobreza agraria subyacente y el narcotr\u00e1fico,<\/strong>\u00a0al combatiente lo transformaron de revolucionario, en desechable. La vinculaci\u00f3n a las organizaciones se da por reclutamiento forzado o por ingresos econ\u00f3micos en dinero o en especie lo que permite la &#8220;desechablizacion&#8221; de los combatientes. Lo que s\u00ed es un desastre para los due\u00f1os de las organizaciones armadas actuales es la ca\u00edda de alijos y armas. M\u00e1s los alijos de drogas y oro que las armas&#8221;, complement\u00f3 el mandatario.<\/p>\n\n\n\n<p>ElTiempo\/Noticias del Meta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente\u00a0Gustavo Petro asegur\u00f3 que alias Iv\u00e1n Mordisco, jefe de una facci\u00f3n de las disidencias de las Farc, est\u00e1 arrinconado.\u00a0 El mandatario se pronunci\u00f3 en la tarde del domingo 10 de octubre, 24 horas despu\u00e9s de que el Ej\u00e9rcito dio de baja a 10 disidentes al mando de &#8216;Mordisco&#8217; durante unos combates en el departamento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-728","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog"},"_links":{"self":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/comments?post=728"}],"version-history":[{"count":1,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/728\/revisions"}],"predecessor-version":[{"id":731,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/728\/revisions\/731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media\/730"}],"wp:attachment":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media?parent=728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/categories?post=728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/tags?post=728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}