{"id":787,"date":"2025-10-22T00:33:12","date_gmt":"2025-10-22T00:33:12","guid":{"rendered":"https:\/\/kioskodeprensa.online\/?p=787"},"modified":"2025-11-04T01:37:18","modified_gmt":"2025-11-04T01:37:18","slug":"san-isidro-de-chichimene-celebra-su-festival-de-la-palma-y-el-aceite","status":"publish","type":"post","link":"https:\/\/kioskodeprensa.online\/index.php\/2025\/10\/22\/san-isidro-de-chichimene-celebra-su-festival-de-la-palma-y-el-aceite\/","title":{"rendered":"San Isidro de Chichimene celebra su Festival de la Palma y el Aceite"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"360\" src=\"https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/RTRTY.png\" alt=\"\" class=\"wp-image-788\" srcset=\"https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/RTRTY.png 474w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/RTRTY-300x228.png 300w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/RTRTY-150x114.png 150w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure><\/div>\n\n\n<p>Ubicado a solo 14 kil\u00f3metros del \u00e1rea urbana de Acac\u00edas, el centro poblado San Isidro de Chichimene se alista para celebrar la octava versi\u00f3n del Festival de la Palma y el Aceite, en honor a San Isidro Labrador, que tendr\u00e1 una variada oferta de actividades culturales, deportivas, reinado, m\u00fasica y artistas invitados, entre otras. El Festival, que cuenta con el apoyo del Gobierno municipal, se iniciar\u00e1 este viernes 19 de septiembre con un desfile de comparsas sobre mitos y leyendas del Llano y una \u2018Joropera\u2019, en el que decenas de parejas bailan al son de joropo por las v\u00edas del centro poblado.<\/p>\n\n\n\n<p>Ese mismo d\u00eda pasado el mediod\u00eda se instalar\u00e1n el Mercado Campesino y la Feria Artesanal y de Emprendimiento, y desde la vereda Loma de Tigre saldr\u00e1 a la 1:00 p.m. la cabalgata, que llegar\u00e1 a San Isidro de Chichimene.<\/p>\n\n\n\n<p>La tarima central, en la que se impondr\u00e1 la banda a las candidatas al VIII Reinado de la Palma y el Aceite, tendr\u00e1 en la primera noche a artistas llaneros y de m\u00fasica popular y bailable.<\/p>\n\n\n\n<p>El s\u00e1bado 20 la programaci\u00f3n contempla la visita de las candidatas del reinado al Mercado Campesino y a la Feria Artesanal y de Emprendimiento, adem\u00e1s de la presentaci\u00f3n por parte de ellas de una muestra folcl\u00f3rica. Adem\u00e1s, habr\u00e1 actividades l\u00fadicas, de aer\u00f3bicos y zumba.<\/p>\n\n\n\n<p>La noche sabatina tendr\u00e1 como show centrales a la m\u00fasica llanera con Jhon Onofre (foto) y el repertorio popular de Jimmy Guti\u00e9rrez.<\/p>\n\n\n\n<p>El \u00faltimo d\u00eda del Festival ser\u00e1 un domingo en el que el deporte ser\u00e1 protagonista, con partidos de f\u00fatbol, la presencia del equipo Sub 20 de Llaneros FC como invitado, y otras actividades deportivas durante la jornada. Y en la noche se cumplir\u00e1 la elecci\u00f3n y coronaci\u00f3n de la Reina del Festival, en medio de un show musical para poner a bailar a los asistentes en el cierre del evento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicado a solo 14 kil\u00f3metros del \u00e1rea urbana de Acac\u00edas, el centro poblado San Isidro de Chichimene se alista para celebrar la octava versi\u00f3n del Festival de la Palma y el Aceite, en honor a San Isidro Labrador, que tendr\u00e1 una variada oferta de actividades culturales, deportivas, reinado, m\u00fasica y artistas invitados, entre otras. El [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,162,19],"tags":[],"class_list":{"0":"post-787","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura","8":"category-gobierno-local","9":"category-noticias"},"_links":{"self":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/comments?post=787"}],"version-history":[{"count":1,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/787\/revisions"}],"predecessor-version":[{"id":789,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/787\/revisions\/789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media\/788"}],"wp:attachment":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media?parent=787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/categories?post=787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/tags?post=787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}