{"id":796,"date":"2025-10-22T00:40:44","date_gmt":"2025-10-22T00:40:44","guid":{"rendered":"https:\/\/kioskodeprensa.online\/?p=796"},"modified":"2025-11-04T01:35:18","modified_gmt":"2025-11-04T01:35:18","slug":"zapateando-por-acacias-espectaculo-para-disfrutar-este-sabado-en-el-festival-del-retorno","status":"publish","type":"post","link":"https:\/\/kioskodeprensa.online\/index.php\/2025\/10\/22\/zapateando-por-acacias-espectaculo-para-disfrutar-este-sabado-en-el-festival-del-retorno\/","title":{"rendered":"\u2018Zapateando por Acac\u00edas\u2019, espect\u00e1culo para disfrutar este s\u00e1bado en el Festival del Retorno"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"502\" height=\"345\" src=\"https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/FFRE.png\" alt=\"\" class=\"wp-image-797\" srcset=\"https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/FFRE.png 502w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/FFRE-300x206.png 300w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/FFRE-150x103.png 150w, https:\/\/kioskodeprensa.online\/wp-content\/uploads\/2025\/10\/FFRE-218x150.png 218w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/figure><\/div>\n\n\n<p>M\u00e1s de 70 academias de baile de joropo ser\u00e1n las protagonistas de un espect\u00e1culo lleno de energ\u00eda, color y mucha m\u00fasica llanera, que llenar\u00e1n hoy (s\u00e1bado) las calles del centro de la ciudad en el evento denominado \u2018Zapateando por Acac\u00edas\u2019.<\/p>\n\n\n\n<p>Miles de personas podr\u00e1n disfrutar el recorrido, que tendr\u00e1 como punto de partida la intersecci\u00f3n de la calle 13 con carrera 23 (v\u00eda nacional), a partir de las 9:00 a.m., y que culminar\u00e1 en el parque principal pasado el mediod\u00eda.<\/p>\n\n\n\n<p>Hoy mismo, sobre las 11:00 a.m. en el complejo ganadero, se har\u00e1 el recibimiento a la \u2018Caravana del Retorno\u2019, una tradici\u00f3n en la que los acacire\u00f1os residenciados especialmente en Bogot\u00e1, llegan a su terru\u00f1o para reencontrarse con sus familias y amigos, y a disfrutar la festividad m\u00e1s importante del a\u00f1o en el municipio.<\/p>\n\n\n\n<p>Por su parte, la nueva sede de la Casa de la Cultura de Acac\u00edas ser\u00e1 epicentro de dos exposiciones para admirar: Una fotogr\u00e1fica sobre la \u2018Historia del Festival del Retorno\u2019 y otra muy atractiva como es la de autos cl\u00e1sicos o antiguos.<\/p>\n\n\n\n<p>Durante la tarde de este s\u00e1bado, la tarima llanera en el parque principal concentrar\u00e1 la atenci\u00f3n de los acacire\u00f1os y de los visitantes. Primero con la presentaci\u00f3n de los participantes de todas las modalidades y categor\u00edas del 5\u00ba. Concurso \u2018Acacire\u00f1o Soy\u2019 y del 50\u00ba. Torneo Internacional de M\u00fasica Llanera.<\/p>\n\n\n\n<p>Ya en la noche, sobre las 7:00 p.m., estar\u00e1n en la misma tarima mostrando sus aptitudes folcl\u00f3ricas llaneras las candidatas al 22\u00ba. Reinado Internacional del Retorno; posteriormente se ver\u00e1 el espect\u00e1culo de apertura del Festival, la presentaci\u00f3n de artistas llaneros locales y el show de las \u2018Damas de la voz recia\u2019, del que hacen parte tres reconocidas voces del canto llanero: Virginia Rocha, Nancy Vargas y Leidy Lara (foto arriba).<\/p>\n\n\n\n<p>Paralela a la tarima llanera, desde las 7:00 p.m. estar\u00e1 tambi\u00e9n disponible la alterna en la Villa Ol\u00edmpica, con la presentaci\u00f3n de DJ\u2019s y artistas locales <em>crossover,<\/em> que ambientar\u00e1n el inicio de una noche con mucha variedad musical; y posteriormente se \u2018prender\u00e1\u2019 la rumba con la agrupaci\u00f3n Los Dotores de la Carranga, el reguetonero Kevin Rold\u00e1n, la orquesta salsera La 33 y la cantante de vallenato Ana del Castillo, quien ser\u00e1 la encargada de cerrar la segunda noche de conciertos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 70 academias de baile de joropo ser\u00e1n las protagonistas de un espect\u00e1culo lleno de energ\u00eda, color y mucha m\u00fasica llanera, que llenar\u00e1n hoy (s\u00e1bado) las calles del centro de la ciudad en el evento denominado \u2018Zapateando por Acac\u00edas\u2019. Miles de personas podr\u00e1n disfrutar el recorrido, que tendr\u00e1 como punto de partida la intersecci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,89,162],"tags":[],"class_list":{"0":"post-796","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura","8":"category-eventos-culturales","9":"category-gobierno-local"},"_links":{"self":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/comments?post=796"}],"version-history":[{"count":1,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/796\/revisions"}],"predecessor-version":[{"id":798,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/posts\/796\/revisions\/798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media\/797"}],"wp:attachment":[{"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/media?parent=796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/categories?post=796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kioskodeprensa.online\/index.php\/wp-json\/wp\/v2\/tags?post=796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}